{"id":271,"date":"2005-07-18T13:34:06","date_gmt":"2005-07-18T11:34:06","guid":{"rendered":"http:\/\/bloggingtom.ch\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/"},"modified":"2005-07-18T13:34:06","modified_gmt":"2005-07-18T11:34:06","slug":"liegestutzen-gegen-pornografie","status":"publish","type":"post","link":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/","title":{"rendered":"Liegest\u00fctzen gegen Pornografie"},"content":{"rendered":"<p>Im indischen Distrikt Balasore geht man neue Wege im Kampf gegen die allgegenw\u00e4rtige Pornografie. Die rund 200 Besucher eines illegalen Pornokinos wurden w\u00e4hrend einer Razzia mit einer Sofortstrafe belegt: Jeder von ihnen musste zehn Liegest\u00fctzen machen. Zudem musste jeder Besucher \u00f6ffentlich schw\u00f6ren, sich nie wieder einen Porno anzusehen.<br \/>\nOffensichtlich erwischten die Beamten auch minderj\u00e4hrige Sexkino-Besucher: Deren Eltern mussten der Strafaktion beiwohnen.<\/p>\n<p>Sachen gibts&#8230;<\/p>\n<p>(via <a href=\"http:\/\/www.spiegel.de\/panorama\/0,1518,365640,00.html\" target=\"_blank\" >SpOn<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im indischen Distrikt Balasore geht man neue Wege im Kampf gegen die allgegenw\u00e4rtige Pornografie. Die rund 200 Besucher eines illegalen Pornokinos wurden w\u00e4hrend einer Razzia mit einer Sofortstrafe belegt: Jeder von ihnen musste zehn Liegest\u00fctzen machen. Zudem musste jeder Besucher \u00f6ffentlich schw\u00f6ren, sich nie wieder einen Porno anzusehen. Offensichtlich erwischten die Beamten auch minderj\u00e4hrige Sexkino-Besucher: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[802,776,803],"class_list":["post-271","post","type-post","status-publish","format-standard","hentry","category-aufgeschnappt","tag-indien","tag-kino","tag-liegestutze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liegest\u00fctzen gegen Pornografie - BloggingTom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"BloggingTom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\"},\"author\":{\"name\":\"BloggingTom\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"headline\":\"Liegest\u00fctzen gegen Pornografie\",\"datePublished\":\"2005-07-18T11:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\"},\"wordCount\":73,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"keywords\":[\"indien\",\"kino\",\"liegest\u00fctze\"],\"articleSection\":[\"Aufgeschnappt\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\",\"name\":\"Liegest\u00fctzen gegen Pornografie - BloggingTom\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\"},\"datePublished\":\"2005-07-18T11:34:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bloggingtom.ch\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liegest\u00fctzen gegen Pornografie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/\",\"name\":\"BloggingTom\",\"description\":\"Die t\u00e4glichen Abenteuer im Cyberspace...\",\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\",\"name\":\"BloggingTom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"caption\":\"BloggingTom\"},\"logo\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/bloggingtom.ch\"],\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liegest\u00fctzen gegen Pornografie - BloggingTom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/","twitter_misc":{"Verfasst von":"BloggingTom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#article","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/"},"author":{"name":"BloggingTom","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"headline":"Liegest\u00fctzen gegen Pornografie","datePublished":"2005-07-18T11:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/"},"wordCount":73,"commentCount":0,"publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"keywords":["indien","kino","liegest\u00fctze"],"articleSection":["Aufgeschnappt"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/","url":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/","name":"Liegest\u00fctzen gegen Pornografie - BloggingTom","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/#website"},"datePublished":"2005-07-18T11:34:06+00:00","breadcrumb":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/07\/18\/liegestutzen-gegen-pornografie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bloggingtom.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Liegest\u00fctzen gegen Pornografie"}]},{"@type":"WebSite","@id":"https:\/\/bloggingtom.ch\/blog\/#website","url":"https:\/\/bloggingtom.ch\/blog\/","name":"BloggingTom","description":"Die t\u00e4glichen Abenteuer im Cyberspace...","publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c","name":"BloggingTom","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","caption":"BloggingTom"},"logo":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/bloggingtom.ch"],"url":"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pa6Ev-4n","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":0,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"wp:attachment":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}