{"id":2528,"date":"2011-02-16T20:38:27","date_gmt":"2011-02-16T19:38:27","guid":{"rendered":"http:\/\/bloggingtom.ch\/?p=2528"},"modified":"2011-02-16T20:38:27","modified_gmt":"2011-02-16T19:38:27","slug":"steve-ballmer-in-zurich-heiter-bis-bewolkt","status":"publish","type":"post","link":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/","title":{"rendered":"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt"},"content":{"rendered":"<p>Keine Frage, Steve war, auch wenn man ihm etwas M\u00fcdigkeit anmerkte, gut aufgelegt am heutigen Microsoft-Event in Z\u00fcrich-Kloten. Es mache Spass, in den heutigen Zeiten in der IT-Industrie zu arbeiten, sagte er, und so beantwortete er auch die Frage, ob er die &#8222;Jungs von Google&#8220; hasse, mit einem klaren Nein. Konkurrenz sei schliesslich wichtig f\u00fcrs Gesch\u00e4ft, aber zu einem Bier mit Noch-Google-CEO Eric Schmidt reiche es dann doch nicht. Weniger, weil er nicht wollte, sondern vielmehr, weil er ihn gar nicht pers\u00f6nlich kenne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"centered\" src=\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg\" alt=\"Steve Ballmer in Z\u00fcrich - I like\" title=\"Steve Ballmer in Z\u00fcrich - I like\" width=\"465\" height=\"326\" \/><\/p>\n<p>Wolkig wie das Wetter draussen wurde es dann bei seinen beiden Keynote vor Entwicklern und, eehm, Entscheidern (&#8222;Business Decision Makers&#8220;). Schliesslich will auch Microsoft beim allgegenw\u00e4rtigen Thema Cloud-Computing mitmischen und Steve verwies denn auch darauf, dass die Cloud-Plattform Windows Azure bereits bei rund 30&#8217;000 Kunden im Einsatz stehe. In Zukunft, so Ballmer, w\u00fcrden immer mehr Firmen keine eigenen Server mehr betreiben, sondern die ben\u00f6tigte Rechenleistung aus einer Cloud beziehen. Mit einer &#8222;Private Edition&#8220; von Azure k\u00f6nnten zudem M\u00f6glichkeiten geschaffen werden, die Clouds in der Schweiz zu betreiben und damit den gesetzlichen Anforderungen f\u00fcr die Lagerung von Daten zu gen\u00fcgen. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"centered\" src=\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-winphone7.jpg\" alt=\"Steve Ballmer in Z\u00fcrich - Windows Phone 7\" title=\"Steve Ballmer in Z\u00fcrich - Windows Phone 7\" width=\"465\" height=\"361\"  \/><\/p>\n<p>Eine heitere bis zufriedene Miene gab es dann zum Handy-Betriebssystem Windows Phone 7. Kein Wunder, denn erst Anfangs Woche konnte Ballmer die Partnerschaft mit Nokia am Mobile World Congress verk\u00fcnden. &#8222;Wir haben bewiesen, dass wir ein einzigartiges Smartphone-Erlebnis mit einem funktionierenden Ecosystem liefern k\u00f6nnen, so Ballmer. Und das kommt offenbar an, denn die Kundenzufriedenheit sei mit 93 Prozent \u00fcberdurchschnittlich hoch. Zahlen zum Marktanteil oder zur Zahl der bisher in der Schweiz abgesetzten WinPhone7-Handys liess sich Daniel Moschin, General Manager Consumer &#038; Online von Microsoft Schweiz, jedoch nicht entlocken. Immerhin gab es mit der Vorstellung der Apps von local.ch, Zattoo und Blick dann doch noch etwas  &#8222;lokales&#8220; zu sehen.<\/p>\n<p>(Photos: Microsoft, <a href=\"http:\/\/roli.me\/\" target=\"_blank\">Roli Keusch<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keine Frage, Steve war, auch wenn man ihm etwas M\u00fcdigkeit anmerkte, gut aufgelegt am heutigen Microsoft-Event in Z\u00fcrich-Kloten. Es mache Spass, in den heutigen Zeiten in der IT-Industrie zu arbeiten, sagte er, und so beantwortete er auch die Frage, ob er die &#8222;Jungs von Google&#8220; hasse, mit einem klaren Nein. Konkurrenz sei schliesslich wichtig f\u00fcrs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2955],"tags":[21,2989,141],"class_list":["post-2528","post","type-post","status-publish","format-standard","hentry","category-events-veranstaltungen","tag-microsoft","tag-steve-ballmer","tag-zurich"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt - BloggingTom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"BloggingTom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\"},\"author\":{\"name\":\"BloggingTom\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"headline\":\"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt\",\"datePublished\":\"2011-02-16T19:38:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\"},\"wordCount\":315,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"image\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg\",\"keywords\":[\"microsoft\",\"steve ballmer\",\"z\u00fcrich\"],\"articleSection\":[\"Events &amp; Veranstaltungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\",\"name\":\"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt - BloggingTom\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg\",\"datePublished\":\"2011-02-16T19:38:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage\",\"url\":\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg\",\"contentUrl\":\"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bloggingtom.ch\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/\",\"name\":\"BloggingTom\",\"description\":\"Die t\u00e4glichen Abenteuer im Cyberspace...\",\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\",\"name\":\"BloggingTom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"caption\":\"BloggingTom\"},\"logo\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/bloggingtom.ch\"],\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt - BloggingTom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/","twitter_misc":{"Verfasst von":"BloggingTom","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#article","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/"},"author":{"name":"BloggingTom","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"headline":"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt","datePublished":"2011-02-16T19:38:27+00:00","mainEntityOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/"},"wordCount":315,"commentCount":1,"publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"image":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage"},"thumbnailUrl":"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg","keywords":["microsoft","steve ballmer","z\u00fcrich"],"articleSection":["Events &amp; Veranstaltungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/","url":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/","name":"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt - BloggingTom","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage"},"image":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage"},"thumbnailUrl":"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg","datePublished":"2011-02-16T19:38:27+00:00","breadcrumb":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#primaryimage","url":"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg","contentUrl":"http:\/\/bloggingtom.ch\/wp-content\/uploads\/2011\/02\/20110216-steve-ballmer-zuerich-ilike.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2011\/02\/16\/steve-ballmer-in-zurich-heiter-bis-bewolkt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bloggingtom.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Steve Ballmer in Z\u00fcrich: Heiter bis bew\u00f6lkt"}]},{"@type":"WebSite","@id":"https:\/\/bloggingtom.ch\/blog\/#website","url":"https:\/\/bloggingtom.ch\/blog\/","name":"BloggingTom","description":"Die t\u00e4glichen Abenteuer im Cyberspace...","publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c","name":"BloggingTom","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","caption":"BloggingTom"},"logo":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/bloggingtom.ch"],"url":"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pa6Ev-EM","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/2528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/comments?post=2528"}],"version-history":[{"count":6,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/2528\/revisions"}],"predecessor-version":[{"id":2536,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/2528\/revisions\/2536"}],"wp:attachment":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/media?parent=2528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/categories?post=2528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/tags?post=2528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}