{"id":1597,"date":"2007-09-16T12:36:12","date_gmt":"2007-09-16T10:36:12","guid":{"rendered":"http:\/\/bloggingtom.ch\/?p=1597"},"modified":"2007-09-16T12:37:19","modified_gmt":"2007-09-16T10:37:19","slug":"12106-neue-beitrage-lesestress-am-sonntag","status":"publish","type":"post","link":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/","title":{"rendered":"12&#8217;106 neue Beitr\u00e4ge: Lesestress am Sonntag"},"content":{"rendered":"<div class=\"img-shadow-right\"><img decoding=\"async\" src=\"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif\" alt=\"Screenshot - Bloglines\" \/><\/div>\n<p><a href=\"http:\/\/www.bloglines.com\" target=\"_blank\" >Bloglines<\/a> scheint mal wieder ziemlichen Schluckauf zu haben. Ganze 12&#8217;106 neue Beitr\u00e4ge sollen aus Sicht des RSS-Readers seit meinem letzten Besuch vor rund 12 Stunden neu geschrieben worden sein. Daran scheint auch der <a href=\"http:\/\/bloggingtom.ch\/archives\/2005\/06\/07\/the-bloglines-plumber\/\" target=\"_top\" >Bloglines Plumber<\/a>, der mich bereits gestern Nacht \u00fcberrascht hat, nichts ge\u00e4ndert zu haben. <\/p>\n<p>Robert &#8222;BasicThinking&#8220; ist zwar f\u00fcr seine hohe Postingfrequenz bekannt, doch dass alleine er in den letzten Stunden 200 neue Beitr\u00e4ge geschrieben haben soll, ist nun doch etwas \u00fcbertrieben&#8230;<\/p>\n<p>Na dann melde ich mich ab: Bis ich die 12&#8217;106 Beitr\u00e4ge gelesen habe, d\u00fcrfte einige Zeit vergehen&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bloglines scheint mal wieder ziemlichen Schluckauf zu haben. Ganze 12&#8217;106 neue Beitr\u00e4ge sollen aus Sicht des RSS-Readers seit meinem letzten Besuch vor rund 12 Stunden neu geschrieben worden sein. Daran scheint auch der Bloglines Plumber, der mich bereits gestern Nacht \u00fcberrascht hat, nichts ge\u00e4ndert zu haben. Robert &#8222;BasicThinking&#8220; ist zwar f\u00fcr seine hohe Postingfrequenz bekannt, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1597","post","type-post","status-publish","format-standard","hentry","category-internet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12&#039;106 neue Beitr\u00e4ge: Lesestress am Sonntag - BloggingTom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"BloggingTom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\"},\"author\":{\"name\":\"BloggingTom\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"headline\":\"12&#8217;106 neue Beitr\u00e4ge: Lesestress am Sonntag\",\"datePublished\":\"2007-09-16T10:36:12+00:00\",\"dateModified\":\"2007-09-16T10:37:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\"},\"wordCount\":99,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"image\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif\",\"articleSection\":[\"Internet\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\",\"name\":\"12'106 neue Beitr\u00e4ge: Lesestress am Sonntag - BloggingTom\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif\",\"datePublished\":\"2007-09-16T10:36:12+00:00\",\"dateModified\":\"2007-09-16T10:37:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage\",\"url\":\"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif\",\"contentUrl\":\"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bloggingtom.ch\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12&#8217;106 neue Beitr\u00e4ge: Lesestress am Sonntag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/\",\"name\":\"BloggingTom\",\"description\":\"Die t\u00e4glichen Abenteuer im Cyberspace...\",\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\",\"name\":\"BloggingTom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"caption\":\"BloggingTom\"},\"logo\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/bloggingtom.ch\"],\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12'106 neue Beitr\u00e4ge: Lesestress am Sonntag - BloggingTom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/","twitter_misc":{"Verfasst von":"BloggingTom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#article","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/"},"author":{"name":"BloggingTom","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"headline":"12&#8217;106 neue Beitr\u00e4ge: Lesestress am Sonntag","datePublished":"2007-09-16T10:36:12+00:00","dateModified":"2007-09-16T10:37:19+00:00","mainEntityOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/"},"wordCount":99,"commentCount":5,"publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"image":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage"},"thumbnailUrl":"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif","articleSection":["Internet"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/","url":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/","name":"12'106 neue Beitr\u00e4ge: Lesestress am Sonntag - BloggingTom","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage"},"image":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage"},"thumbnailUrl":"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif","datePublished":"2007-09-16T10:36:12+00:00","dateModified":"2007-09-16T10:37:19+00:00","breadcrumb":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#primaryimage","url":"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif","contentUrl":"http:\/\/bloggingtom.ch\/wp-images\/ownimg\/articles\/20070916-bloglines.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2007\/09\/16\/12106-neue-beitrage-lesestress-am-sonntag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bloggingtom.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"12&#8217;106 neue Beitr\u00e4ge: Lesestress am Sonntag"}]},{"@type":"WebSite","@id":"https:\/\/bloggingtom.ch\/blog\/#website","url":"https:\/\/bloggingtom.ch\/blog\/","name":"BloggingTom","description":"Die t\u00e4glichen Abenteuer im Cyberspace...","publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c","name":"BloggingTom","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","caption":"BloggingTom"},"logo":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/bloggingtom.ch"],"url":"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pa6Ev-pL","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/1597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/comments?post=1597"}],"version-history":[{"count":0,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/1597\/revisions"}],"wp:attachment":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/media?parent=1597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/categories?post=1597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/tags?post=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}