{"id":11,"date":"2005-02-17T08:58:45","date_gmt":"2005-02-17T07:58:45","guid":{"rendered":"http:\/\/www.bruehwiler.info\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/"},"modified":"2005-04-18T14:52:40","modified_gmt":"2005-04-18T12:52:40","slug":"warnung-tiefgekuhlte-poulets-greifen-an","status":"publish","type":"post","link":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/","title":{"rendered":"Warnung: Tiefgek\u00fchlte Poulets greifen an!"},"content":{"rendered":"<p>Unglaublich, aber kann man der seri\u00f6sen ARD-Tagesschau misstrauen? Beim St\u00f6bern im <a href=\"http:\/\/www.shopblogger.de\/archives\/209-Tiefkuehlhaehnchen-greifen-an....html\" target=\"_blank\">Shopblogger!<\/a> brach ich unvermittelt in schallendes Gel\u00e4chter aus, denn wer rechnet schon mit angreifenden Poulets? Dazu noch wenn sie tiefgek\u00fchlt sind? Aber das scheint gem\u00e4ss einer Nachricht der ARD-Tagesschau in Australien offenbar der Fall zu sein.<br \/>\nIn Newcastle seien in den vergangenen Wochen mindestens drei Wohnh\u00e4user besch\u00e4digt worden, &#8222;als Tiefk\u00fchlh\u00e4hnchen mit grosser Wucht aufprallten und zum Teil sogar Ziegeld\u00e4cher durchschlugen&#8220;, teilte die Polizei mit.<\/p>\n<p>Einfach k\u00f6stlich&#8230; Den ganzen Artikel der ARD-Tagesschau findet ihr <a href=\"http:\/\/www.tagesschau.de\/aktuell\/meldungen\/0,1185,OID4054918_REF1,00.html\" target=\"_blank\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unglaublich, aber kann man der seri\u00f6sen ARD-Tagesschau misstrauen? Beim St\u00f6bern im Shopblogger! brach ich unvermittelt in schallendes Gel\u00e4chter aus, denn wer rechnet schon mit angreifenden Poulets? Dazu noch wenn sie tiefgek\u00fchlt sind? Aber das scheint gem\u00e4ss einer Nachricht der ARD-Tagesschau in Australien offenbar der Fall zu sein. In Newcastle seien in den vergangenen Wochen mindestens [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[70,73,74,72,71],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-aufgeschnappt","tag-ard","tag-haehnchen","tag-polizei","tag-poulet","tag-tagesschau"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warnung: Tiefgek\u00fchlte Poulets greifen an! - BloggingTom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"BloggingTom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\"},\"author\":{\"name\":\"BloggingTom\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"headline\":\"Warnung: Tiefgek\u00fchlte Poulets greifen an!\",\"datePublished\":\"2005-02-17T07:58:45+00:00\",\"dateModified\":\"2005-04-18T12:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"keywords\":[\"ard\",\"haehnchen\",\"polizei\",\"poulet\",\"tagesschau\"],\"articleSection\":[\"Aufgeschnappt\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\",\"name\":\"Warnung: Tiefgek\u00fchlte Poulets greifen an! - BloggingTom\",\"isPartOf\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\"},\"datePublished\":\"2005-02-17T07:58:45+00:00\",\"dateModified\":\"2005-04-18T12:52:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bloggingtom.ch\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warnung: Tiefgek\u00fchlte Poulets greifen an!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#website\",\"url\":\"https:\/\/bloggingtom.ch\/blog\/\",\"name\":\"BloggingTom\",\"description\":\"Die t\u00e4glichen Abenteuer im Cyberspace...\",\"publisher\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c\",\"name\":\"BloggingTom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g\",\"caption\":\"BloggingTom\"},\"logo\":{\"@id\":\"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/bloggingtom.ch\"],\"url\":\"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warnung: Tiefgek\u00fchlte Poulets greifen an! - BloggingTom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/","twitter_misc":{"Verfasst von":"BloggingTom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#article","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/"},"author":{"name":"BloggingTom","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"headline":"Warnung: Tiefgek\u00fchlte Poulets greifen an!","datePublished":"2005-02-17T07:58:45+00:00","dateModified":"2005-04-18T12:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"keywords":["ard","haehnchen","polizei","poulet","tagesschau"],"articleSection":["Aufgeschnappt"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/","url":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/","name":"Warnung: Tiefgek\u00fchlte Poulets greifen an! - BloggingTom","isPartOf":{"@id":"https:\/\/bloggingtom.ch\/blog\/#website"},"datePublished":"2005-02-17T07:58:45+00:00","dateModified":"2005-04-18T12:52:40+00:00","breadcrumb":{"@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bloggingtom.ch\/blog\/archives\/2005\/02\/17\/warnung-tiefgekuhlte-poulets-greifen-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bloggingtom.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Warnung: Tiefgek\u00fchlte Poulets greifen an!"}]},{"@type":"WebSite","@id":"https:\/\/bloggingtom.ch\/blog\/#website","url":"https:\/\/bloggingtom.ch\/blog\/","name":"BloggingTom","description":"Die t\u00e4glichen Abenteuer im Cyberspace...","publisher":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloggingtom.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/f6c8d3d5f30c10217b69ac72723e9d1c","name":"BloggingTom","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17c2b6a2966fc102465cf177587d359e4dac41adfaab355352baee5d5d46f277?s=96&d=mm&r=g","caption":"BloggingTom"},"logo":{"@id":"https:\/\/bloggingtom.ch\/blog\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/bloggingtom.ch"],"url":"https:\/\/bloggingtom.ch\/blog\/archives\/author\/bloggingtom\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pa6Ev-b","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloggingtom.ch\/blog\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}